{"id":118770,"date":"2026-09-01T21:59:49","date_gmt":"2026-09-02T01:59:49","guid":{"rendered":"https:\/\/deportesdigital.com.ve\/public\/?p=118770"},"modified":"2026-09-01T23:48:11","modified_gmt":"2026-09-02T03:48:11","slug":"talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla","status":"publish","type":"post","link":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/","title":{"rendered":"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla"},"content":{"rendered":"<p><strong><em>Prospectos del Zulia dan el salto a la pelota colombiana.<\/em><\/strong><\/p>\n<hr \/>\n<p><strong><em>Nota de Prensa:<\/em><\/strong> El talento de la regi\u00f3n vuelve a brillar en el escenario internacional. Los j\u00f3venes lanzadores zulianos <strong>Eudomar Caridad Jr.<\/strong> (derecho) y <strong>Raul Gotera<\/strong> (zurdo) firmaron su compromiso oficial con la novena de los <strong>Leones de Barranquilla<\/strong> para disputar la temporada 2026-2027 de la pelota profesional colombiana.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-118773 aligncenter\" src=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-4.00.01-PM.jpeg\" alt=\"\" width=\"548\" height=\"411\" \/><\/p>\n<p>Voceros de la \u00a0Liga de B\u00e9isbol Mayor del Estado Zulia (<em><strong>LIBEMEZ<\/strong><\/em>), informaron. Ambos serpentineros son producto y activos participantes del programa <strong>LIBEMEZ<\/strong>, una iniciativa impulsada por Asobeisbol Zulia cuyo prop\u00f3sito principal es mantener en constante actividad y desarrollo competitivo al talento beisbol\u00edstico de la regi\u00f3n durante todo el a\u00f1o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-118772 aligncenter\" src=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-3.58.17-PM.jpeg\" alt=\"\" width=\"566\" height=\"425\" \/><\/p>\n<p><strong>Abriendo puertas al talento emergente<\/strong><\/p>\n<p>Esta importante contrataci\u00f3n marca el inicio de una nueva y prometedora etapa en el camino profesional de ambos atletas. Asimismo, representa una ventana de esperanza y motivaci\u00f3n para aquellos peloteros de 17 a\u00f1os en adelante que, pese a poseer un gran talento en el terreno de juego, contin\u00faan batallando por una oportunidad dorada que impulse sus carreras hacia el estrellato internacional.<\/p>\n<p><strong><em>Sigue esta y otras #Noticias ingresando a nuestras plataformas digitales Deportes Digital, en Instagram, Facebook, Twitter, y en nuestros grupos de Whatsapp y Telegram.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prospectos del Zulia dan el salto a la pelota colombiana. Nota de Prensa: El talento de la regi\u00f3n vuelve a brillar en el escenario internacional. Los j\u00f3venes lanzadores zulianos Eudomar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":118771,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-118770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla - Deportes Digital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla - Deportes Digital\" \/>\n<meta property=\"og:description\" content=\"Prospectos del Zulia dan el salto a la pelota colombiana. Nota de Prensa: El talento de la regi\u00f3n vuelve a brillar en el escenario internacional. Los j\u00f3venes lanzadores zulianos Eudomar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Deportes Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DeportesDigitalZulia25\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T01:59:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T03:48:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"963\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"luisg15\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@deporteszulia\" \/>\n<meta name=\"twitter:site\" content=\"@deporteszulia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"luisg15\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/\"},\"author\":{\"name\":\"luisg15\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/person\\\/57d2f23f17d761b1672066d1905e88a0\"},\"headline\":\"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla\",\"datePublished\":\"2026-09-02T01:59:49+00:00\",\"dateModified\":\"2026-09-02T03:48:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg\",\"articleSection\":[\"B\u00e9isbol\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/\",\"name\":\"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla - Deportes Digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg\",\"datePublished\":\"2026-09-02T01:59:49+00:00\",\"dateModified\":\"2026-09-02T03:48:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg\",\"width\":963,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#website\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\",\"name\":\"Deportes Digital\",\"description\":\"Solo Deportes\",\"publisher\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\",\"name\":\"Deportes Digital\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1677066431475.png?fit=1032%2C624&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1677066431475.png?fit=1032%2C624&ssl=1\",\"width\":1032,\"height\":624,\"caption\":\"Deportes Digital\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeportesDigitalZulia25\",\"https:\\\/\\\/x.com\\\/deporteszulia\",\"https:\\\/\\\/www.instagram.com\\\/deportesdigitalzulia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/person\\\/57d2f23f17d761b1672066d1905e88a0\",\"name\":\"luisg15\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"caption\":\"luisg15\"},\"description\":\"Medio de Comunicaci\u00f3n digital dedicado al deporte menor\",\"sameAs\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\"],\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/author\\\/luisg15\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla - Deportes Digital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/","og_locale":"es_ES","og_type":"article","og_title":"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla - Deportes Digital","og_description":"Prospectos del Zulia dan el salto a la pelota colombiana. Nota de Prensa: El talento de la regi\u00f3n vuelve a brillar en el escenario internacional. Los j\u00f3venes lanzadores zulianos Eudomar [&hellip;]","og_url":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/","og_site_name":"Deportes Digital","article_publisher":"https:\/\/www.facebook.com\/DeportesDigitalZulia25","article_published_time":"2026-09-02T01:59:49+00:00","article_modified_time":"2026-09-02T03:48:11+00:00","og_image":[{"width":963,"height":1280,"url":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg","type":"image\/jpeg"}],"author":"luisg15","twitter_card":"summary_large_image","twitter_creator":"@deporteszulia","twitter_site":"@deporteszulia","twitter_misc":{"Escrito por":"luisg15","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#article","isPartOf":{"@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/"},"author":{"name":"luisg15","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/person\/57d2f23f17d761b1672066d1905e88a0"},"headline":"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla","datePublished":"2026-09-02T01:59:49+00:00","dateModified":"2026-09-02T03:48:11+00:00","mainEntityOfPage":{"@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#organization"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#primaryimage"},"thumbnailUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg","articleSection":["B\u00e9isbol"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/","url":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/","name":"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla - Deportes Digital","isPartOf":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#primaryimage"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#primaryimage"},"thumbnailUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg","datePublished":"2026-09-02T01:59:49+00:00","dateModified":"2026-09-02T03:48:11+00:00","breadcrumb":{"@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#primaryimage","url":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg","contentUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-4.01.39-PM.jpeg","width":963,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/deportesdigital.com.ve\/public\/talentos-zulianos-al-beisbol-profesional-eudomar-caridad-jr-y-ruben-gotera-firman-con-los-leones-de-barranquilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/deportesdigital.com.ve\/public\/"},{"@type":"ListItem","position":2,"name":"Talentos zulianos al b\u00e9isbol profesional: Eudomar Caridad Jr. y Raul Gotera firman con los Leones de Barranquilla"}]},{"@type":"WebSite","@id":"https:\/\/deportesdigital.com.ve\/public\/#website","url":"https:\/\/deportesdigital.com.ve\/public\/","name":"Deportes Digital","description":"Solo Deportes","publisher":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deportesdigital.com.ve\/public\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/deportesdigital.com.ve\/public\/#organization","name":"Deportes Digital","url":"https:\/\/deportesdigital.com.ve\/public\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2023\/09\/1677066431475.png?fit=1032%2C624&ssl=1","contentUrl":"https:\/\/i0.wp.com\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2023\/09\/1677066431475.png?fit=1032%2C624&ssl=1","width":1032,"height":624,"caption":"Deportes Digital"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeportesDigitalZulia25","https:\/\/x.com\/deporteszulia","https:\/\/www.instagram.com\/deportesdigitalzulia\/"]},{"@type":"Person","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/person\/57d2f23f17d761b1672066d1905e88a0","name":"luisg15","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","caption":"luisg15"},"description":"Medio de Comunicaci\u00f3n digital dedicado al deporte menor","sameAs":["https:\/\/deportesdigital.com.ve\/public"],"url":"https:\/\/deportesdigital.com.ve\/public\/author\/luisg15\/"}]}},"_links":{"self":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/118770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/comments?post=118770"}],"version-history":[{"count":2,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/118770\/revisions"}],"predecessor-version":[{"id":118778,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/118770\/revisions\/118778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media\/118771"}],"wp:attachment":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media?parent=118770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/categories?post=118770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/tags?post=118770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}