{"id":114367,"date":"2026-03-25T13:50:34","date_gmt":"2026-03-25T17:50:34","guid":{"rendered":"https:\/\/deportesdigital.com.ve\/public\/?p=114367"},"modified":"2026-03-25T13:50:34","modified_gmt":"2026-03-25T17:50:34","slug":"jessire-rivas-triplico-oro-en-el-del-circuito-speed-track-european-series","status":"publish","type":"post","link":"https:\/\/deportesdigital.com.ve\/public\/jessire-rivas-triplico-oro-en-el-del-circuito-speed-track-european-series\/","title":{"rendered":"Jessir\u00e9 Rivas triplic\u00f3 oro en el del circuito Speed Track European Series"},"content":{"rendered":"<p><em><strong>El pr\u00f3ximo destino de la venezolana ser\u00e1n del 4 al 6 de abril el\u00a0Torneo Tres Pistas\u00a0en Valence D\u2019 Agen, Francia, y del 9 al 12 de ese mes disputar\u00e1 certamen\u00a0Terra do Infante\u00a0en Lagos, Portugal.<\/strong><\/em><\/p>\n<hr \/>\n<p><strong><em>Prensa Mindeporte<\/em><\/strong><strong><em>:<\/em><\/strong> La barinesa Jessir\u00e9 Rivas brill\u00f3 al conquista<strong>r tres medallas de oro y dos plata en pruebas de velocidad y fondo\u00a0<\/strong>durante el Speed Track Series en el Trofeo de Internacional Villa de Gij\u00f3n en el inicio del circuito Speed Track European Series en tierras espa\u00f1olas.<\/p>\n<p>La competencia avalada por la World Skate Europe\u00a0 se desarroll\u00f3 en la pista Manuel L\u00f3pez \u201cManol\u00edn\u201d\u00a0 del complejo deportivo de Moreda, en Guij\u00f3n, y agrup\u00f3 a<strong>\u00a0600 patinadores de talla mundial<\/strong>.<\/p>\n<p>Rivas mostr\u00f3 en su perfil personal en la red social Instagram su satisfacci\u00f3n por los resultados obtenidos y asegur\u00f3 que el nivel competitivo le permiti\u00f3\u00a0<strong>ofrecer su mejor desempe\u00f1o en el patin\u00f3dromo espa\u00f1ol.<\/strong><\/p>\n<p>\u201cCon esa fuerza y esa fe en el coraz\u00f3n viv\u00ed cada metro de esta semana en Gij\u00f3n.\u00a0<strong>Cada carrera me record\u00f3 por qu\u00e9 amo este deporte y por qu\u00e9 sigo luchando con tanta pasi\u00f3n por mis sue\u00f1os<\/strong>. A mis rivales doy gracias por la intensidad, la entrega y el respeto en pista. Competir con ustedes me exige m\u00e1s, me impulsa a crecer y me hace una mejor atleta\u201d, expres\u00f3 la criolla.<\/p>\n<p><strong>Patinadora integral<\/strong><\/p>\n<p>La participaci\u00f3n en el torneo la consolida como la\u00a0<strong>patinadora venezolana m\u00e1s integral\u00a0<\/strong>al dominar pruebas de velocidad y fondo. Obtuvo dos medallas de oro en las pruebas 5.000 metros eliminaci\u00f3n, 1.000 metros sprint y una plata en 200 metros dual TT.<\/p>\n<p>Rivas guarda un r\u00e9cord a su favor en este certamen, se convirti\u00f3 tambi\u00e9n como la m\u00e1xima\u00a0<strong>dominadora en las anteriores ediciones de 2024 y 2025.<\/strong><\/p>\n<p>El pr\u00f3ximo destino de la venezolana ser\u00e1n del 4 al 6 de abril el<strong>\u00a0Torneo Tres Pistas\u00a0<\/strong>en Valence d\u2019Agen, Francia, y del 9 al 12 de ese mes disputar\u00e1 certamen\u00a0<strong>Terra do Infante<\/strong>\u00a0en Lagos, Portugal.<\/p>\n<p><strong><em>Sigue esta y otras #Noticias ingresando a nuestras plataformas digitales Deportes Digital, en Instagram, Facebook, Twitter, y en nuestros grupos de Whatsapp y Telegram<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo destino de la venezolana ser\u00e1n del 4 al 6 de abril el\u00a0Torneo Tres Pistas\u00a0en Valence D\u2019 Agen, Francia, y del 9 al 12 de ese mes disputar\u00e1 certamen\u00a0Terra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":114368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-114367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otrosdeportes","clearfix"],"_links":{"self":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/comments?post=114367"}],"version-history":[{"count":1,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114367\/revisions"}],"predecessor-version":[{"id":114369,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114367\/revisions\/114369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media\/114368"}],"wp:attachment":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media?parent=114367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/categories?post=114367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/tags?post=114367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}