{"id":114352,"date":"2026-03-24T19:37:16","date_gmt":"2026-03-24T23:37:16","guid":{"rendered":"https:\/\/deportesdigital.com.ve\/public\/?p=114352"},"modified":"2026-03-24T19:37:16","modified_gmt":"2026-03-24T23:37:16","slug":"la-escuela-de-futbol-sala-de-luz-celebra-un-ano-de-metas-alcanzadas","status":"publish","type":"post","link":"https:\/\/deportesdigital.com.ve\/public\/la-escuela-de-futbol-sala-de-luz-celebra-un-ano-de-metas-alcanzadas\/","title":{"rendered":"La Escuela de F\u00fatbol Sala de LUZ celebra un a\u00f1o de metas alcanzadas"},"content":{"rendered":"<p><strong><em>Este crecimiento es fruto de la constancia: hoy contamos con una estructura consolidada en las categor\u00edas Sub-10, Sub-12, Sub-14, Sub-16 y Sub-18.<\/em><\/strong><\/p>\n<hr \/>\n<p><strong><em>Prensa Luz Deportes:<\/em><\/strong> Lo que comenz\u00f3 como el sue\u00f1o de un solo ni\u00f1o en su primera convocatoria, hoy es una vibrante realidad que llena de vida y orgullo el gimnasio \u00abLino Connell\u00bb de la Direcci\u00f3n de Deportes de la Universidad del Zulia (LUZ).<\/p>\n<p>Al cumplirse el primer aniversario de la escuela de f\u00fatbol sala, celebramos la integraci\u00f3n de 36 j\u00f3venes promesas que, d\u00eda tras d\u00eda, se forman bajo nuestra identidad acad\u00e9mica y deportiva.<\/p>\n<p>Este crecimiento es fruto de la constancia: hoy contamos con una estructura consolidada en las categor\u00edas Sub-10, Sub-12, Sub-14, Sub-16 y Sub-18, donde cada entrenamiento es un paso hacia la excelencia.<\/p>\n<p>La celebraci\u00f3n, realizada el pasado s\u00e1bado 21 de marzo, reuni\u00f3 a los protagonistas de esta hermosa obra.<\/p>\n<p>La programaci\u00f3n incluy\u00f3 palabras de Carlos D\u00edaz, director de Deportes de LUZ e impulsor de esta iniciativa, as\u00ed como la entrega de reconocimientos a los atletas m\u00e1s destacados por parte del brazo ejecutor del proyecto, el entrenador Carlos Pi\u00f1ero.<\/p>\n<p>Tambi\u00e9n hubo una sesi\u00f3n de entrenamiento especial para los padres y un partido amistoso inter escuadras.<\/p>\n<p>En este corto pero intenso recorrido, la escuela ha sumado experiencias valiosas, como su participaci\u00f3n en las dos ediciones del torneo \u00abPrimer Toque\u00bb y la conquista del primer t\u00edtulo en el campeonato del Liceo Jos\u00e9 Ram\u00f3n Y\u00e9pez (categor\u00eda Sub-16).<\/p>\n<p>Estos logros son el cimiento de un proyecto mayor: formar el talento humano que, muy pronto, nutrir\u00e1 las filas de alto rendimiento para representar con orgullo a nuestra instituci\u00f3n en los retos venideros.<\/p>\n<p>Nada de esto ser\u00eda posible sin el pilar fundamental de nuestra escuela: los padres, representantes y amigos. Su apoyo incondicional es el motor que transforma la disciplina en esperanza y el esfuerzo en resultados.<\/p>\n<p><strong><em>Sigue esta y otras #Noticias ingresando a nuestras plataformas digitales Deportes Digital, en Instagram, Facebook, Twitter, y en nuestros grupos de Whatsapp y Telegram<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este crecimiento es fruto de la constancia: hoy contamos con una estructura consolidada en las categor\u00edas Sub-10, Sub-12, Sub-14, Sub-16 y Sub-18. Prensa Luz Deportes: Lo que comenz\u00f3 como el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":114353,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-114352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol","clearfix"],"_links":{"self":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/comments?post=114352"}],"version-history":[{"count":1,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114352\/revisions"}],"predecessor-version":[{"id":114354,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114352\/revisions\/114354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media\/114353"}],"wp:attachment":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media?parent=114352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/categories?post=114352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/tags?post=114352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}