{"id":114326,"date":"2026-03-23T00:51:50","date_gmt":"2026-03-23T04:51:50","guid":{"rendered":"https:\/\/deportesdigital.com.ve\/public\/?p=114326"},"modified":"2026-03-23T00:51:50","modified_gmt":"2026-03-23T04:51:50","slug":"los-comecandela-ganan-a-pioneros-y-mantienen-su-invicto","status":"publish","type":"post","link":"https:\/\/deportesdigital.com.ve\/public\/los-comecandela-ganan-a-pioneros-y-mantienen-su-invicto\/","title":{"rendered":"Los Comecandela ganan a Pioneros y mantienen su invicto"},"content":{"rendered":"<p><strong><em>Gaiteros regresa este lunes a la acci\u00f3n para calibrar fuerzas con Cocodrilos de Caracas, juego est\u00e1 pautado en el PEBA<\/em><\/strong><strong><em>.<\/em><\/strong><\/p>\n<hr \/>\n<p><strong><em>\u00a0<\/em><\/strong><strong><em>Prensa Gaiteros del Zulia:<\/em><\/strong> Gaiteros del Zulia contin\u00faa demostrando su gran momento en el arranque de la temporada 2026 de la SPB, su nueva v\u00edctima fue Pioneros del \u00c1vila a quienes derrotaron con abultado marcador de 102 x 66.<\/p>\n<p>Luego de un inicio dubitativo en los primeros cinco minutos del primer cuarto, los musicales tomaron el control de las acciones restando 40 segundos para la culminaci\u00f3n del mismo cuando igualaron a 21 tantos, un doble de Nazhiah Carter sirvi\u00f3 para que los due\u00f1os de casa cerraran el parcial 23 x 21.<\/p>\n<p>En el segundo cuarto Gaiteros inicio la primera andanada de puntos en combinaci\u00f3n con una magistral defensa de \u00c1ngel Blanco quien logro secar al capit\u00e1n avile\u00f1o Heissler Guillent, el aporte del banco de suplentes fue determinante en este tramo del compromiso logrando 15 de los 24 puntos del periodo, sus principales actores fueron Carter con 8 y Jes\u00fas \u00abLa Torta\u00bb Mart\u00ednez con 6 contables.<\/p>\n<p>Tras la pausa del medio tiempo, emergi\u00f3 otro protagonista proveniente de la segunda unidad Andre Nation quien en combinaci\u00f3n con Albert Arias llevaron la voz cantante del equipo musical para finalizar con un 26 x 18 totalizando 73 x 52.<\/p>\n<p>Los Comecandelas llegaron al \u00faltimo periodo con diferencia de 21 puntos, con ese colch\u00f3n de ventaja el Mago Julio Duquela le dio la oportunidad de jugar a toda su plantilla, Yanitson Quintero aprovecho al m\u00e1ximo los 16:32 minutos que trabajo aportando 7 unidades, 6 rebotes, 2 estafas y una asistencia, lo propio hizo Albert Arias quien finalizo con 9 cartones m\u00e1s 8 tableros, un momento emocionante vivieron los presentes en el PEBA, restando 4:28 ingreso el novel Manuel \u00abTapipita\u00bb Barrios quien logro capturar su primer rebote y anotar 2 sus dos primeros puntos como jugador profesional.<\/p>\n<p>La menci\u00f3n honor\u00edfica del juego se la llevo Jes\u00fas \u00abLa Torta \u00abMart\u00ednez quien logro su primer doble \/ doble de la temporada con 14 unidades y 10 rebotes en 17:25 minutos sobre la duela<\/p>\n<p>Jugadores destacados:<\/p>\n<ul>\n<li><strong>Jesse Zarzuela 20 puntos, 4 asistencias, 1 rebote, 2 <\/strong><\/li>\n<li><strong>Nazhiah Carter 18 puntos, 6 rebotes, 3 asistencias, 2 <\/strong><\/li>\n<li><strong>Jes\u00fas Mart\u00ednez 14 unidades y 10 capturas<\/strong><\/li>\n<li><strong>Andre Nation 12 tantos, 3 repartos, 3 rebotes, 2 recuperaciones<\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong>Gaiteros (6\/0) regresa ma\u00f1ana a la acci\u00f3n para calibrar fuerzas con Cocodrilos de Caracas (5\/1), el juego est\u00e1 pautado para las 7:00 p.m en el PEBA<strong>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gaiteros regresa este lunes a la acci\u00f3n para calibrar fuerzas con Cocodrilos de Caracas, juego est\u00e1 pautado en el PEBA. \u00a0Prensa Gaiteros del Zulia: Gaiteros del Zulia contin\u00faa demostrando su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":114327,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-114326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","clearfix"],"_links":{"self":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/comments?post=114326"}],"version-history":[{"count":1,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114326\/revisions"}],"predecessor-version":[{"id":114328,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/114326\/revisions\/114328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media\/114327"}],"wp:attachment":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media?parent=114326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/categories?post=114326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/tags?post=114326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}