{"id":109725,"date":"2025-10-25T23:39:06","date_gmt":"2025-10-26T03:39:06","guid":{"rendered":"https:\/\/deportesdigital.com.ve\/public\/?p=109725"},"modified":"2025-10-25T23:39:06","modified_gmt":"2025-10-26T03:39:06","slug":"salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup","status":"publish","type":"post","link":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/","title":{"rendered":"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup"},"content":{"rendered":"<p><strong><em>La emoci\u00f3n contin\u00faa este s\u00e1bado con la segunda jornada, que presenta dos atractivos encuentros.<\/em><\/strong><\/p>\n<hr \/>\n<p><strong><em>Jos\u00e9 Gil Deportes Digital\/Maracaibo:<\/em><\/strong> El baloncesto de primera categor\u00eda inaugur\u00f3 su fiesta este viernes con el vibrante salto entre dos de la <strong>Primera Edici\u00f3n de la Gaiteros Cup 2025<\/strong> en el gimnasio Pedro El\u00edas Belisario Aponte de Maracaibo. El evento promete ser un hito en el deporte regional, sirviendo de vitrina para el talento zuliano a nivel amateur que aspira al profesionalismo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-109715 aligncenter\" src=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup1.jpg\" alt=\"\" width=\"825\" height=\"396\" srcset=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup1.jpg 681w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup1-300x144.jpg 300w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup1-435x209.jpg 435w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\" \/><\/p>\n<p>La inauguraci\u00f3n cont\u00f3 con la presencia de destacadas figuras, incluyendo a <strong>Omar Barrios<\/strong>, presidente del equipo Gaiteros del Zulia, <strong>Juan Barrios<\/strong>, presidente de la Gaiteros Cup, y <strong>Wilfredo Garc\u00eda<\/strong>, de la comisi\u00f3n t\u00e9cnica del evento.<\/p>\n<p>La jornada inaugural estuvo cargada de acci\u00f3n:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-109714 aligncenter\" src=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup2.jpg\" alt=\"\" width=\"650\" height=\"368\" srcset=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup2.jpg 650w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup2-300x170.jpg 300w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup2-435x246.jpg 435w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p><strong>Encuentro de Creadores de Contenido:<\/strong> El evento arranc\u00f3 con el triunfo del equipo de <strong>Maracaibo Space<\/strong> 19-14 sobre <strong>Catatumbo Sport<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-109727 aligncenter\" src=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup4.jpg\" alt=\"\" width=\"746\" height=\"497\" srcset=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup4.jpg 648w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup4-300x200.jpg 300w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup4-435x290.jpg 435w\" sizes=\"auto, (max-width: 746px) 100vw, 746px\" \/><\/p>\n<p><strong>Primer Juego Oficial:<\/strong> <strong>Titanes del Caujaro<\/strong> se impuso con contundencia 59-37 ante el quinteto de <strong>Tritones del Lago<\/strong>. El Jugador M\u00e1s Valioso (JMV) del encuentro fue <strong>Jhon M\u00e9ndez<\/strong> (Titanes), quien registr\u00f3 13 puntos, 1 rebote y 1 asistencia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-109726 aligncenter\" src=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup3.jpg\" alt=\"\" width=\"809\" height=\"494\" srcset=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup3.jpg 632w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup3-300x183.jpg 300w, https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup3-435x266.jpg 435w\" sizes=\"auto, (max-width: 809px) 100vw, 809px\" \/><\/p>\n<p><strong>Juego Estelar:<\/strong> La noche cerr\u00f3 con la victoria de <strong>El Pinar Basketball<\/strong> con marcador de 71-50 sobre <strong>Fiorella Basketball<\/strong>. El JMV fue <strong>Jes\u00fas Villanueva<\/strong> (El Pinar), con una destacada actuaci\u00f3n de 19 puntos, 6 rebotes y 1 asistencia.<\/p>\n<p>La emoci\u00f3n contin\u00fao este s\u00e1bado con la segunda jornada, \u00a0con el triunfo del equipo de Inversiones Mc Pollo 81-46 contra el quinteto de Los Mangos, el jugador MVP del encuentro Miguel Fern\u00e1ndez, con actuaci\u00f3n de 17 puntos, 5 rebotes y 6 asistencias.<\/p>\n<p>La primera fecha cerro el triunfo del equipo de Fiorella ante Titanes del Caujaro con pizarra 73-55, el jugador MVP del Jos\u00e9 Rodas, con 15 puntos, 4 rebotes, 2 asistencias.<\/p>\n<p>La acci\u00f3n de Gaiteros Cup volver\u00e1 el pr\u00f3ximo 29 de octubre desde las 07 de la noche ene le tabloncillo del Pedro El\u00edas Belisario Aponte de Maracaibo.<\/p>\n<p><strong><em>Sigue esta y otras #Noticias ingresando a nuestras plataformas digitales Deportes Digital, en Instagram, Facebook, Twitter, y en nuestros grupos de Whatsapp y Telegram<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La emoci\u00f3n contin\u00faa este s\u00e1bado con la segunda jornada, que presenta dos atractivos encuentros. Jos\u00e9 Gil Deportes Digital\/Maracaibo: El baloncesto de primera categor\u00eda inaugur\u00f3 su fiesta este viernes con el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":109728,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-109725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup - Deportes Digital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup - Deportes Digital\" \/>\n<meta property=\"og:description\" content=\"La emoci\u00f3n contin\u00faa este s\u00e1bado con la segunda jornada, que presenta dos atractivos encuentros. Jos\u00e9 Gil Deportes Digital\/Maracaibo: El baloncesto de primera categor\u00eda inaugur\u00f3 su fiesta este viernes con el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/\" \/>\n<meta property=\"og:site_name\" content=\"Deportes Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DeportesDigitalZulia25\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-26T03:39:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup98.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"818\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"luisg15\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@deporteszulia\" \/>\n<meta name=\"twitter:site\" content=\"@deporteszulia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"luisg15\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/\"},\"author\":{\"name\":\"luisg15\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/person\\\/57d2f23f17d761b1672066d1905e88a0\"},\"headline\":\"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup\",\"datePublished\":\"2025-10-26T03:39:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/\"},\"wordCount\":365,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cup98.jpg\",\"articleSection\":[\"Baloncesto\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/\",\"name\":\"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup - Deportes Digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cup98.jpg\",\"datePublished\":\"2025-10-26T03:39:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cup98.jpg\",\"contentUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cup98.jpg\",\"width\":800,\"height\":818},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#website\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\",\"name\":\"Deportes Digital\",\"description\":\"Solo Deportes\",\"publisher\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\",\"name\":\"Deportes Digital\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1677066431475.png?fit=1032%2C624&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1677066431475.png?fit=1032%2C624&ssl=1\",\"width\":1032,\"height\":624,\"caption\":\"Deportes Digital\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeportesDigitalZulia25\",\"https:\\\/\\\/x.com\\\/deporteszulia\",\"https:\\\/\\\/www.instagram.com\\\/deportesdigitalzulia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/person\\\/57d2f23f17d761b1672066d1905e88a0\",\"name\":\"luisg15\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"caption\":\"luisg15\"},\"description\":\"Medio de Comunicaci\u00f3n digital dedicado al deporte menor\",\"sameAs\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\"],\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/author\\\/luisg15\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup - Deportes Digital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/","og_locale":"es_ES","og_type":"article","og_title":"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup - Deportes Digital","og_description":"La emoci\u00f3n contin\u00faa este s\u00e1bado con la segunda jornada, que presenta dos atractivos encuentros. Jos\u00e9 Gil Deportes Digital\/Maracaibo: El baloncesto de primera categor\u00eda inaugur\u00f3 su fiesta este viernes con el [&hellip;]","og_url":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/","og_site_name":"Deportes Digital","article_publisher":"https:\/\/www.facebook.com\/DeportesDigitalZulia25","article_published_time":"2025-10-26T03:39:06+00:00","og_image":[{"width":800,"height":818,"url":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup98.jpg","type":"image\/jpeg"}],"author":"luisg15","twitter_card":"summary_large_image","twitter_creator":"@deporteszulia","twitter_site":"@deporteszulia","twitter_misc":{"Escrito por":"luisg15","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#article","isPartOf":{"@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/"},"author":{"name":"luisg15","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/person\/57d2f23f17d761b1672066d1905e88a0"},"headline":"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup","datePublished":"2025-10-26T03:39:06+00:00","mainEntityOfPage":{"@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/"},"wordCount":365,"commentCount":0,"publisher":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#organization"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#primaryimage"},"thumbnailUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup98.jpg","articleSection":["Baloncesto"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/","url":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/","name":"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup - Deportes Digital","isPartOf":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#primaryimage"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#primaryimage"},"thumbnailUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup98.jpg","datePublished":"2025-10-26T03:39:06+00:00","breadcrumb":{"@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#primaryimage","url":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup98.jpg","contentUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/10\/cup98.jpg","width":800,"height":818},{"@type":"BreadcrumbList","@id":"https:\/\/deportesdigital.com.ve\/public\/salto-entre-dos-en-la-fiesta-del-baloncesto-zuliano-arranco-la-primera-edicion-de-la-gaiteros-cup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/deportesdigital.com.ve\/public\/"},{"@type":"ListItem","position":2,"name":"Salto entre dos en la fiesta del baloncesto zuliano Arranc\u00f3 la Primera Edici\u00f3n de la Gaiteros Cup"}]},{"@type":"WebSite","@id":"https:\/\/deportesdigital.com.ve\/public\/#website","url":"https:\/\/deportesdigital.com.ve\/public\/","name":"Deportes Digital","description":"Solo Deportes","publisher":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deportesdigital.com.ve\/public\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/deportesdigital.com.ve\/public\/#organization","name":"Deportes Digital","url":"https:\/\/deportesdigital.com.ve\/public\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2023\/09\/1677066431475.png?fit=1032%2C624&ssl=1","contentUrl":"https:\/\/i0.wp.com\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2023\/09\/1677066431475.png?fit=1032%2C624&ssl=1","width":1032,"height":624,"caption":"Deportes Digital"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeportesDigitalZulia25","https:\/\/x.com\/deporteszulia","https:\/\/www.instagram.com\/deportesdigitalzulia\/"]},{"@type":"Person","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/person\/57d2f23f17d761b1672066d1905e88a0","name":"luisg15","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","caption":"luisg15"},"description":"Medio de Comunicaci\u00f3n digital dedicado al deporte menor","sameAs":["https:\/\/deportesdigital.com.ve\/public"],"url":"https:\/\/deportesdigital.com.ve\/public\/author\/luisg15\/"}]}},"_links":{"self":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/109725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/comments?post=109725"}],"version-history":[{"count":1,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/109725\/revisions"}],"predecessor-version":[{"id":109729,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/109725\/revisions\/109729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media\/109728"}],"wp:attachment":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media?parent=109725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/categories?post=109725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/tags?post=109725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}