{"id":100537,"date":"2025-01-20T09:35:44","date_gmt":"2025-01-20T13:35:44","guid":{"rendered":"https:\/\/deportesdigital.com.ve\/public\/?p=100537"},"modified":"2025-01-20T09:35:44","modified_gmt":"2025-01-20T13:35:44","slug":"bravos-gana-el-primero-de-la-final","status":"publish","type":"post","link":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/","title":{"rendered":"Bravos gana el primero de la final"},"content":{"rendered":"<p><strong><em>Los insulares <\/em><\/strong><strong><em>reencontrar\u00e1n en el segundo de la serie decisiva ante Cardenales.<\/em><\/strong><\/p>\n<hr \/>\n<p><strong><em>Prensa Bravos de Margarita:<\/em><\/strong> Bravos\u00a0de Margarita se impuso en el primer compromiso de la Gran Final, en el nido de Cardenales de Lara, 4 rayitas por 2, este domingo.<\/p>\n<p>\u201cFue tremendo juego de pelota, el primero de la final, detalles, juego cerrado, pitcheo, bateo oportuno, como han venido jugando todo el a\u00f1o. De verdad, estoy contento y orgulloso de este grupo de muchachos, que est\u00e1n dejando todo\u201d, declar\u00f3 el m\u00e1nager Jos\u00e9 Moreno, tras concretarse la victoria insular.<\/p>\n<p>Por su parte, Alexi Amarista, que se fue de 5-2 con par de dobles, dos empujadas y una anotada, dijo: \u201cEste es un equipo que est\u00e1 hecho para grandes cosas, unos Bravos de Margarita, que, con el favor de Dios, con la fe que siempre hemos tenido, con esa qu\u00edmica y esa actitud que tenemos durante el partido, nos va a llevar a lograr el primer campeonato para la organizaci\u00f3n\u201d.<\/p>\n<p>Asimismo, agreg\u00f3: Cada compa\u00f1ero est\u00e1 enfocado en lo que tiene que hacer y eso es lo que se ejecut\u00f3 el d\u00eda de hoy. Gracias a Dios nos salieron las cosas, seguiremos dando lo mejor, para que esa fanaticada est\u00e9 contenta\u201d.<\/p>\n<p>Margarita inaugur\u00f3 el score en la tercera entrada con doble del \u00abNinja\u00bb Amarista, que mand\u00f3 al plato a Jos\u00e9 \u201cTil\u00edn\u201d Mart\u00ednez y a Lorenzo Cedrola. De inmediato, el segunda base de los margarite\u00f1os tambi\u00e9n pis\u00f3 el plato, fletado por rodado del \u201cB\u00fafalo\u201d Wilson Ramos.<\/p>\n<p>Sin embargo, en la baja del episodio los locales se acercaron con hit de Rangel Ravelo, que empuj\u00f3 dos, anotadas por Al\u00ed S\u00e1nchez y Gorkys Hern\u00e1ndez.<\/p>\n<p>Pero en el cuarto episodio, los insulares aumentaron la ventaja con elevado de sacrificio de \u00abLa Hormiga At\u00f3mica\u00bb Cedrola, que empuj\u00f3 a Herlis Rodr\u00edguez.<\/p>\n<p>La victoria monticular fue para F\u00e9lix Doubront (2-1), tras cinco entradas de labor en las que abanic\u00f3 a dos, dio tres boletos, recibi\u00f3 par de carreras y ocho imparables.<\/p>\n<p>\u201cEsta es una plaza que se llena, con bastante bulla y algarab\u00eda, enfrentando a un equipo, que, de verdad, se reforz\u00f3 bien, un line up bien bueno, que puede hacer da\u00f1o en cualquier momento. Pero el enfoque que uno puede tener, positivamente, es siempre estar arriba de ellos, lanzar ese pitcheo clave para sacarlos de balance y eso fue lo que funcion\u00f3. Complicaciones si tuve, pero luego reseti\u00e9, me mantuve calmado, lanzando el mejor pitcheo que pod\u00eda, para sacarlos de out\u201d, cont\u00f3 el zurdo bravo.<\/p>\n<p>El rev\u00e9s fue para Jimmy Endersby (2-2), tras tres innings lanzados en los que recibi\u00f3 siete imparables, cuatro carreras, un pasaporte y un ponche.<\/p>\n<p>Ambos conjuntos se reencontrar\u00e1n en el segundo de la serie decisiva, este lunes, a partir de las 7:00 de la noche, en el estadio Don Antonio Herrera Guti\u00e9rrez, en Barquisimeto. Por los margarite\u00f1os tomar\u00e1 la bola el derecho criollo Jes\u00fas Vargas.<\/p>\n<p><strong><em>Sigue esta y otras\u00a0<\/em><\/strong><a href=\"https:\/\/z-p15.www.instagram.com\/explore\/tags\/noticias\/\"><strong><em>#Noticias<\/em><\/strong><\/a><strong><em>\u00a0ingresando a nuestras plataformas digitales Deportes Digital, en Instagram, Facebook, Twitter, y en nuestros grupos de Whatsapp y Telegram.<\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los insulares reencontrar\u00e1n en el segundo de la serie decisiva ante Cardenales. Prensa Bravos de Margarita: Bravos\u00a0de Margarita se impuso en el primer compromiso de la Gran Final, en el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":100538,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3459,679,600,2931],"class_list":["post-100537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","tag-braos","tag-final","tag-gana","tag-lvbp-temporada24-25","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bravos gana el primero de la final - Deportes Digital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bravos gana el primero de la final - Deportes Digital\" \/>\n<meta property=\"og:description\" content=\"Los insulares reencontrar\u00e1n en el segundo de la serie decisiva ante Cardenales. Prensa Bravos de Margarita: Bravos\u00a0de Margarita se impuso en el primer compromiso de la Gran Final, en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/\" \/>\n<meta property=\"og:site_name\" content=\"Deportes Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DeportesDigitalZulia25\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-20T13:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/01\/5034.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"622\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"luisg15\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@deporteszulia\" \/>\n<meta name=\"twitter:site\" content=\"@deporteszulia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"luisg15\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/\"},\"author\":{\"name\":\"luisg15\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/person\\\/57d2f23f17d761b1672066d1905e88a0\"},\"headline\":\"Bravos gana el primero de la final\",\"datePublished\":\"2025-01-20T13:35:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/\"},\"wordCount\":528,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5034.jpg\",\"keywords\":[\"braos\",\"final\",\"gana\",\"lvbp temporada24-25\"],\"articleSection\":[\"B\u00e9isbol\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/\",\"name\":\"Bravos gana el primero de la final - Deportes Digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5034.jpg\",\"datePublished\":\"2025-01-20T13:35:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5034.jpg\",\"contentUrl\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/5034.jpg\",\"width\":622,\"height\":457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/bravos-gana-el-primero-de-la-final\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bravos gana el primero de la final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#website\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\",\"name\":\"Deportes Digital\",\"description\":\"Solo Deportes\",\"publisher\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#organization\",\"name\":\"Deportes Digital\",\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1677066431475.png?fit=1032%2C624&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/deportesdigital.com.ve\\\/public\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1677066431475.png?fit=1032%2C624&ssl=1\",\"width\":1032,\"height\":624,\"caption\":\"Deportes Digital\"},\"image\":{\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeportesDigitalZulia25\",\"https:\\\/\\\/x.com\\\/deporteszulia\",\"https:\\\/\\\/www.instagram.com\\\/deportesdigitalzulia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/#\\\/schema\\\/person\\\/57d2f23f17d761b1672066d1905e88a0\",\"name\":\"luisg15\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g\",\"caption\":\"luisg15\"},\"description\":\"Medio de Comunicaci\u00f3n digital dedicado al deporte menor\",\"sameAs\":[\"https:\\\/\\\/deportesdigital.com.ve\\\/public\"],\"url\":\"https:\\\/\\\/deportesdigital.com.ve\\\/public\\\/author\\\/luisg15\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bravos gana el primero de la final - Deportes Digital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/","og_locale":"es_ES","og_type":"article","og_title":"Bravos gana el primero de la final - Deportes Digital","og_description":"Los insulares reencontrar\u00e1n en el segundo de la serie decisiva ante Cardenales. Prensa Bravos de Margarita: Bravos\u00a0de Margarita se impuso en el primer compromiso de la Gran Final, en el [&hellip;]","og_url":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/","og_site_name":"Deportes Digital","article_publisher":"https:\/\/www.facebook.com\/DeportesDigitalZulia25","article_published_time":"2025-01-20T13:35:44+00:00","og_image":[{"width":622,"height":457,"url":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/01\/5034.jpg","type":"image\/jpeg"}],"author":"luisg15","twitter_card":"summary_large_image","twitter_creator":"@deporteszulia","twitter_site":"@deporteszulia","twitter_misc":{"Escrito por":"luisg15","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#article","isPartOf":{"@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/"},"author":{"name":"luisg15","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/person\/57d2f23f17d761b1672066d1905e88a0"},"headline":"Bravos gana el primero de la final","datePublished":"2025-01-20T13:35:44+00:00","mainEntityOfPage":{"@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/"},"wordCount":528,"commentCount":0,"publisher":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#organization"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#primaryimage"},"thumbnailUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/01\/5034.jpg","keywords":["braos","final","gana","lvbp temporada24-25"],"articleSection":["B\u00e9isbol"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/","url":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/","name":"Bravos gana el primero de la final - Deportes Digital","isPartOf":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#primaryimage"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#primaryimage"},"thumbnailUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/01\/5034.jpg","datePublished":"2025-01-20T13:35:44+00:00","breadcrumb":{"@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#primaryimage","url":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/01\/5034.jpg","contentUrl":"https:\/\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2025\/01\/5034.jpg","width":622,"height":457},{"@type":"BreadcrumbList","@id":"https:\/\/deportesdigital.com.ve\/public\/bravos-gana-el-primero-de-la-final\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/deportesdigital.com.ve\/public\/"},{"@type":"ListItem","position":2,"name":"Bravos gana el primero de la final"}]},{"@type":"WebSite","@id":"https:\/\/deportesdigital.com.ve\/public\/#website","url":"https:\/\/deportesdigital.com.ve\/public\/","name":"Deportes Digital","description":"Solo Deportes","publisher":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deportesdigital.com.ve\/public\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/deportesdigital.com.ve\/public\/#organization","name":"Deportes Digital","url":"https:\/\/deportesdigital.com.ve\/public\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2023\/09\/1677066431475.png?fit=1032%2C624&ssl=1","contentUrl":"https:\/\/i0.wp.com\/deportesdigital.com.ve\/public\/wp-content\/uploads\/2023\/09\/1677066431475.png?fit=1032%2C624&ssl=1","width":1032,"height":624,"caption":"Deportes Digital"},"image":{"@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeportesDigitalZulia25","https:\/\/x.com\/deporteszulia","https:\/\/www.instagram.com\/deportesdigitalzulia\/"]},{"@type":"Person","@id":"https:\/\/deportesdigital.com.ve\/public\/#\/schema\/person\/57d2f23f17d761b1672066d1905e88a0","name":"luisg15","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d424b63ebd2800d281b824141af3d97c1332dfdda83d70b2057085925af58a3?s=96&d=mm&r=g","caption":"luisg15"},"description":"Medio de Comunicaci\u00f3n digital dedicado al deporte menor","sameAs":["https:\/\/deportesdigital.com.ve\/public"],"url":"https:\/\/deportesdigital.com.ve\/public\/author\/luisg15\/"}]}},"_links":{"self":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/100537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/comments?post=100537"}],"version-history":[{"count":1,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/100537\/revisions"}],"predecessor-version":[{"id":100539,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/posts\/100537\/revisions\/100539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media\/100538"}],"wp:attachment":[{"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/media?parent=100537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/categories?post=100537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportesdigital.com.ve\/public\/wp-json\/wp\/v2\/tags?post=100537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}